{"id":23,"name":"Michel Gehring","url":"","description":"","link":"https:\/\/blo-freunde.de\/en\/author\/mailglut-berlin\/","slug":"mailglut-berlin","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/blo-freunde.de\/en\/wp-json\/wp\/v2\/users\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blo-freunde.de\/en\/wp-json\/wp\/v2\/users"}]}}